{"id":17009,"date":"2023-03-02T11:45:24","date_gmt":"2023-03-02T10:45:24","guid":{"rendered":"https:\/\/www.botek.de\/?page_id=17009"},"modified":"2023-06-20T07:32:38","modified_gmt":"2023-06-20T05:32:38","slug":"pilot-drills-in-solid-carbide-design-for-twist-drills","status":"publish","type":"page","link":"https:\/\/www.botek.de\/en\/contact\/pilot-drills-in-solid-carbide-design-for-twist-drills\/","title":{"rendered":"Pilot drills in solid carbide design for twist drills"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><script>\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gform_legacy_markup_wrapper gform-theme--no-framework gf-bigger-font-form_wrapper' data-form-theme='legacy' data-form-index='0' id='gform_wrapper_34' style='display:none'>\n                        <div class='gform_heading'>\n                            <p class='gform_description'>Solid carbide pilot drill for solid carbide twist drills Type 158-08, Type 158-07<\/p>\n                        <\/div><form method='post' enctype='multipart\/form-data'  id='gform_34' class='gf-bigger-font-form' action='\/en\/wp-json\/wp\/v2\/pages\/17009' data-formid='34' novalidate>\n                        <div class='gform-body gform_body'><ul id='gform_fields_34' class='gform_fields top_label form_sublabel_below description_below validation_below'><li id=\"field_34_89\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_89'><span class='gform-field-label__text'>Email<\/span><\/label><div class='ginput_container'><input name='input_89' id='input_34_89' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_34_89'>This field is for validation purposes and should be left unchanged.<\/div><\/li><li id=\"field_34_2\" class=\"gfield gfield--type-section gsection field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h2 class=\"gsection_title\"><\/h2><\/li><li id=\"field_34_1\" class=\"gfield gfield--type-checkbox gfield--type-choice gf_list_inline gf-list-correct-margin field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible gfield--choice-align-vertical\"  ><label class='gfield_label gform-field-label screen-reader-text gfield_label_before_complex' ><span class='gform-field-label__text'><\/span><\/label><div class='ginput_container ginput_container_checkbox'><ul class='gfield_checkbox' id='input_34_1'><li class='gchoice gchoice_34_1_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_1.1' type='checkbox'  value='Inquiry'  id='choice_34_1_1'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_34_1_1' id='label_34_1_1' class='gform-field-label gform-field-label--type-inline'>Inquiry<\/label>\n\t\t\t\t\t\t\t<\/li><li class='gchoice gchoice_34_1_2'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_1.2' type='checkbox'  value='Order'  id='choice_34_1_2'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_34_1_2' id='label_34_1_2' class='gform-field-label gform-field-label--type-inline'>Order<\/label>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/li><li id=\"field_34_76\" class=\"gfield gfield--type-section gsection field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h2 class=\"gsection_title\"><\/h2><\/li><li id=\"field_34_13\" class=\"gfield gfield--type-text gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_13'><span class='gform-field-label__text'>Name:<\/span><span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_13' id='input_34_13' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_4\" class=\"gfield gfield--type-text gf_right_half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_4'><span class='gform-field-label__text'>Order \/ inquiry number:<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_4' id='input_34_4' type='text' value='' class='medium'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_14\" class=\"gfield gfield--type-text gf_left_half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_14'><span class='gform-field-label__text'>Phone:<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_14' id='input_34_14' type='text' value='' class='medium'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_82\" class=\"gfield gfield--type-email gf_right_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_82'><span class='gform-field-label__text'>E-Mail:<\/span><span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_82' id='input_34_82' type='email' value='' class='medium'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/li><li id=\"field_34_79\" class=\"gfield gfield--type-html gfield_html gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><\/li><!-- close the html field li -->\n<\/ul><!-- close the list -->\n<fieldset id=\"fieldset_1\"><!-- open the first fieldset -->\n<ul class=\"gform_fields\"><!-- reopen the list --><\/li><li id=\"field_34_5\" class=\"gfield gfield--type-html gf_left_half gfield_html gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h3 style=\"margin-bottom: 0px;\">Address<\/h3>\n<p>&nbsp;<\/p><\/li><li id=\"field_34_7\" class=\"gfield gfield--type-text gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_7'><span class='gform-field-label__text'>Company:<\/span><span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_7' id='input_34_7' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_9\" class=\"gfield gfield--type-text gf_left_half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_9'><span class='gform-field-label__text'>Street \/ House number:<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_9' id='input_34_9' type='text' value='' class='medium'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_11\" class=\"gfield gfield--type-text gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_11'><span class='gform-field-label__text'>Postal code \/ City:<\/span><span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_11' id='input_34_11' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_86\" class=\"gfield gfield--type-text gfield--width-full gf_left_half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_86'><span class='gform-field-label__text'>Country:<\/span><span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_86' id='input_34_86' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_80\" class=\"gfield gfield--type-html gfield_html gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><\/li><!-- close the html field li -->\n<\/ul><!-- close the list -->\n<\/fieldset><!-- close the first fieldset -->\n<fieldset id=\"fieldset_2\"><!-- open the second fieldset -->\n<ul class=\"gform_fields\"><!-- reopen the list --><\/li><li id=\"field_34_6\" class=\"gfield gfield--type-html gf_right_half gfield_html gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h3  style=\"margin-bottom: 0px;\">Shipping address <\/h3>\n<p>(if different)<\/p><\/li><li id=\"field_34_8\" class=\"gfield gfield--type-text gf_right_half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_8'><span class='gform-field-label__text'>Company:<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_8' id='input_34_8' type='text' value='' class='medium'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_10\" class=\"gfield gfield--type-text gf_right_half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_10'><span class='gform-field-label__text'>Street \/ House number:<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_10' id='input_34_10' type='text' value='' class='medium'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_12\" class=\"gfield gfield--type-text gf_right_half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_12'><span class='gform-field-label__text'>Postal code \/ City:<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_12' id='input_34_12' type='text' value='' class='medium'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_87\" class=\"gfield gfield--type-text gfield--width-full gf_right_half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_87'><span class='gform-field-label__text'>Country:<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_87' id='input_34_87' type='text' value='' class='medium'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_81\" class=\"gfield gfield--type-html gfield_html gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><\/li><!-- close the html field li -->\n<\/ul><!-- close the list -->\n<\/fieldset><!-- close the second fieldset --><\/li><li id=\"field_34_15\" class=\"gfield gfield--type-section gsection field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h2 class=\"gsection_title\"><\/h2><\/li><li id=\"field_34_16\" class=\"gfield gfield--type-checkbox gfield--type-choice gf_list_4col field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible gfield--choice-align-vertical\"  ><label class='gfield_label gform-field-label gfield_label_before_complex' ><span class='gform-field-label__text'>Drilling method:<\/span><\/label><div class='ginput_container ginput_container_checkbox'><ul class='gfield_checkbox' id='input_34_16'><li class='gchoice gchoice_34_16_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_16.1' type='checkbox'  value='Solid drilling'  id='choice_34_16_1'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_34_16_1' id='label_34_16_1' class='gform-field-label gform-field-label--type-inline'>Solid drilling<\/label>\n\t\t\t\t\t\t\t<\/li><li class='gchoice gchoice_34_16_2'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_16.2' type='checkbox'  value='Oblique drilling'  id='choice_34_16_2'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_34_16_2' id='label_34_16_2' class='gform-field-label gform-field-label--type-inline'>Oblique drilling<\/label>\n\t\t\t\t\t\t\t<\/li><li class='gchoice gchoice_34_16_3'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_16.3' type='checkbox'  value='Precast bore'  id='choice_34_16_3'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_34_16_3' id='label_34_16_3' class='gform-field-label gform-field-label--type-inline'>Precast bore<\/label>\n\t\t\t\t\t\t\t<\/li><li class='gchoice gchoice_34_16_4'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_16.4' type='checkbox'  value='Blind hole'  id='choice_34_16_4'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_34_16_4' id='label_34_16_4' class='gform-field-label gform-field-label--type-inline'>Blind hole<\/label>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/li><li id=\"field_34_17\" class=\"gfield gfield--type-checkbox gfield--type-choice gf_list_4col field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible gfield--choice-align-vertical\"  ><label class='gfield_label gform-field-label gfield_label_before_complex' ><span class='gform-field-label__text'>Material:<\/span><\/label><div class='ginput_container ginput_container_checkbox'><ul class='gfield_checkbox' id='input_34_17'><li class='gchoice gchoice_34_17_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_17.1' type='checkbox'  value='Steel'  id='choice_34_17_1'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_34_17_1' id='label_34_17_1' class='gform-field-label gform-field-label--type-inline'>Steel<\/label>\n\t\t\t\t\t\t\t<\/li><li class='gchoice gchoice_34_17_2'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_17.2' type='checkbox'  value='GG\/GGG'  id='choice_34_17_2'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_34_17_2' id='label_34_17_2' class='gform-field-label gform-field-label--type-inline'>GG\/GGG<\/label>\n\t\t\t\t\t\t\t<\/li><li class='gchoice gchoice_34_17_3'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_17.3' type='checkbox'  value='AL-Si-Leg'  id='choice_34_17_3'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_34_17_3' id='label_34_17_3' class='gform-field-label gform-field-label--type-inline'>AL-Si-Leg<\/label>\n\t\t\t\t\t\t\t<\/li><li class='gchoice gchoice_34_17_4'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_17.4' type='checkbox'  value='Other material'  id='choice_34_17_4'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_34_17_4' id='label_34_17_4' class='gform-field-label gform-field-label--type-inline'>Other material<\/label>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/li><li id=\"field_34_88\" class=\"gfield gfield--type-text gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_88'><span class='gform-field-label__text'>Other material:<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_88' id='input_34_88' type='text' value='' class='large'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_18\" class=\"gfield gfield--type-checkbox gfield--type-choice gf_list_4col field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible gfield--choice-align-vertical\"  ><label class='gfield_label gform-field-label gfield_label_before_complex' ><span class='gform-field-label__text'>Machine:<\/span><\/label><div class='ginput_container ginput_container_checkbox'><ul class='gfield_checkbox' id='input_34_18'><li class='gchoice gchoice_34_18_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_18.1' type='checkbox'  value='Turning \/ milling center'  id='choice_34_18_1'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_34_18_1' id='label_34_18_1' class='gform-field-label gform-field-label--type-inline'>Turning \/ milling center<\/label>\n\t\t\t\t\t\t\t<\/li><li class='gchoice gchoice_34_18_2'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_18.2' type='checkbox'  value='Lathe'  id='choice_34_18_2'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_34_18_2' id='label_34_18_2' class='gform-field-label gform-field-label--type-inline'>Lathe<\/label>\n\t\t\t\t\t\t\t<\/li><li class='gchoice gchoice_34_18_3'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_18.3' type='checkbox'  value='Deep hole drilling machine'  id='choice_34_18_3'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_34_18_3' id='label_34_18_3' class='gform-field-label gform-field-label--type-inline'>Deep hole drilling machine<\/label>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/li><li id=\"field_34_19\" class=\"gfield gfield--type-section gsection field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h2 class=\"gsection_title\"><\/h2><\/li><li id=\"field_34_84\" class=\"gfield gfield--type-fileupload field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='gform_browse_button_34_84'><span class='gform-field-label__text'>Upload tool \/ material drawing:<\/span><\/label><div class='ginput_container ginput_container_fileupload'><div id='gform_multifile_upload_34_84' data-settings='{&quot;runtimes&quot;:&quot;html5,flash,html4&quot;,&quot;browse_button&quot;:&quot;gform_browse_button_34_84&quot;,&quot;container&quot;:&quot;gform_multifile_upload_34_84&quot;,&quot;drop_element&quot;:&quot;gform_drag_drop_area_34_84&quot;,&quot;filelist&quot;:&quot;gform_preview_34_84&quot;,&quot;unique_names&quot;:true,&quot;file_data_name&quot;:&quot;file&quot;,&quot;url&quot;:&quot;https:\\\/\\\/www.botek.de\\\/?gf_page=91bdb9bc78117d7&quot;,&quot;flash_swf_url&quot;:&quot;https:\\\/\\\/www.botek.de\\\/wp-includes\\\/js\\\/plupload\\\/plupload.flash.swf&quot;,&quot;silverlight_xap_url&quot;:&quot;https:\\\/\\\/www.botek.de\\\/wp-includes\\\/js\\\/plupload\\\/plupload.silverlight.xap&quot;,&quot;filters&quot;:{&quot;mime_types&quot;:[{&quot;title&quot;:&quot;Allowed Files&quot;,&quot;extensions&quot;:&quot;jpg,jpeg,png,pdf,stp,dxf&quot;}],&quot;max_file_size&quot;:&quot;20971520b&quot;},&quot;multipart&quot;:true,&quot;urlstream_upload&quot;:false,&quot;multipart_params&quot;:{&quot;form_id&quot;:34,&quot;field_id&quot;:84,&quot;_gform_file_upload_nonce_34_84&quot;:&quot;250be65af0&quot;},&quot;gf_vars&quot;:{&quot;max_files&quot;:&quot;5&quot;,&quot;message_id&quot;:&quot;gform_multifile_messages_34_84&quot;,&quot;disallowed_extensions&quot;:[&quot;php&quot;,&quot;asp&quot;,&quot;aspx&quot;,&quot;cmd&quot;,&quot;csh&quot;,&quot;bat&quot;,&quot;html&quot;,&quot;htm&quot;,&quot;hta&quot;,&quot;jar&quot;,&quot;exe&quot;,&quot;com&quot;,&quot;js&quot;,&quot;lnk&quot;,&quot;htaccess&quot;,&quot;phar&quot;,&quot;phtml&quot;,&quot;ps1&quot;,&quot;ps2&quot;,&quot;php3&quot;,&quot;php4&quot;,&quot;php5&quot;,&quot;php6&quot;,&quot;py&quot;,&quot;rb&quot;,&quot;tmp&quot;]}}' class='gform_fileupload_multifile'>\n\t\t\t\t\t\t\t\t\t\t<div id='gform_drag_drop_area_34_84' class='gform_drop_area gform-theme-field-control'>\n\t\t\t\t\t\t\t\t\t\t\t<span class='gform_drop_instructions'>Drop files here or <\/span>\n\t\t\t\t\t\t\t\t\t\t\t<button type='button' id='gform_browse_button_34_84' class='button gform_button_select_files gform-theme-button gform-theme-button--control' aria-describedby=\"gfield_upload_rules_34_84\"  >Select files<\/button>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div><span class='gfield_description gform_fileupload_rules' id='gfield_upload_rules_34_84'>Accepted file types: jpg, jpeg, png, pdf, stp, dxf, Max. file size: 20 MB, Max. files: 5.<\/span><ul class='validation_message--hidden-on-empty gform-ul-reset' id='gform_multifile_messages_34_84'><\/ul> <div id='gform_preview_34_84' class='ginput_preview_list'><\/div><\/div><\/li><li id=\"field_34_83\" class=\"gfield gfield--type-section gsection field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h2 class=\"gsection_title\"><\/h2><\/li><li id=\"field_34_20\" class=\"gfield gfield--type-select field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_20'><span class='gform-field-label__text'>Drill:<\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_20' id='input_34_20' class='small gfield_select'     aria-invalid=\"false\" ><option value='1' >1<\/option><option value='2' >2<\/option><option value='3' >3<\/option><option value='4' >4<\/option><option value='5' >5<\/option><\/select><\/div><\/li><li id=\"field_34_22\" class=\"gfield gfield--type-html gfield_html gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h3>Drill 1<\/h3><\/li><li id=\"field_34_27\" class=\"gfield gfield--type-text gf_first_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_27'><span class='gform-field-label__text'>\u00d8 (DC)<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_27' id='input_34_27' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_32\" class=\"gfield gfield--type-text gf_second_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_32'><span class='gform-field-label__text'>Length (OAL)<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_32' id='input_34_32' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_37\" class=\"gfield gfield--type-text gf_third_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_37'><span class='gform-field-label__text'>Drilling depth (mm)<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_37' id='input_34_37' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_42\" class=\"gfield gfield--type-text gf_fourth_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_42'><span class='gform-field-label__text'>Driver dimensions (DCONxLSC\/LS)<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_42' id='input_34_42' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_47\" class=\"gfield gfield--type-text gf_first_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_47'><span class='gform-field-label__text'>Driver No.<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_47' id='input_34_47' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_52\" class=\"gfield gfield--type-text gf_second_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_52'><span class='gform-field-label__text'>Coating<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_52' id='input_34_52' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_57\" class=\"gfield gfield--type-text gf_third_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_57'><span class='gform-field-label__text'>Pieces<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_57' id='input_34_57' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_62\" class=\"gfield gfield--type-text gf_fourth_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_62'><span class='gform-field-label__text'>Delivery date<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_62' id='input_34_62' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_23\" class=\"gfield gfield--type-html gfield_html gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h3>Drill 2<\/h3><\/li><li id=\"field_34_28\" class=\"gfield gfield--type-text gf_first_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_28'><span class='gform-field-label__text'>\u00d8 (DC)<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_28' id='input_34_28' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_33\" class=\"gfield gfield--type-text gf_second_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_33'><span class='gform-field-label__text'>Length (OAL)<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_33' id='input_34_33' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_38\" class=\"gfield gfield--type-text gf_third_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_38'><span class='gform-field-label__text'>Drilling depth (mm)<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_38' id='input_34_38' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_45\" class=\"gfield gfield--type-text gf_fourth_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_45'><span class='gform-field-label__text'>Driver dimensions (DCONxLSC\/LS)<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_45' id='input_34_45' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_48\" class=\"gfield gfield--type-text gf_first_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_48'><span class='gform-field-label__text'>Driver No.<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_48' id='input_34_48' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_53\" class=\"gfield gfield--type-text gf_second_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_53'><span class='gform-field-label__text'>Coating<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_53' id='input_34_53' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_58\" class=\"gfield gfield--type-text gf_third_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_58'><span class='gform-field-label__text'>Pieces<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_58' id='input_34_58' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_63\" class=\"gfield gfield--type-text gf_fourth_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_63'><span class='gform-field-label__text'>Delivery date<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_63' id='input_34_63' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_24\" class=\"gfield gfield--type-html gfield_html gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h3>Drill 3<\/h3><\/li><li id=\"field_34_29\" class=\"gfield gfield--type-text gf_first_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_29'><span class='gform-field-label__text'>\u00d8 (DC)<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_29' id='input_34_29' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_34\" class=\"gfield gfield--type-text gf_second_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_34'><span class='gform-field-label__text'>Length (OAL)<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_34' id='input_34_34' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_39\" class=\"gfield gfield--type-text gf_third_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_39'><span class='gform-field-label__text'>Drilling depth (mm)<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_39' id='input_34_39' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_44\" class=\"gfield gfield--type-text gf_fourth_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_44'><span class='gform-field-label__text'>Driver dimensions (DCONxLSC\/LS)<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_44' id='input_34_44' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_49\" class=\"gfield gfield--type-text gf_first_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_49'><span class='gform-field-label__text'>Driver No.<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_49' id='input_34_49' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_54\" class=\"gfield gfield--type-text gf_second_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_54'><span class='gform-field-label__text'>Coating<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_54' id='input_34_54' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_59\" class=\"gfield gfield--type-text gf_third_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_59'><span class='gform-field-label__text'>Pieces<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_59' id='input_34_59' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_64\" class=\"gfield gfield--type-text gf_fourth_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_64'><span class='gform-field-label__text'>Delivery date<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_64' id='input_34_64' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_25\" class=\"gfield gfield--type-html gfield_html gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h3>Drill 4<\/h3><\/li><li id=\"field_34_30\" class=\"gfield gfield--type-text gf_first_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_30'><span class='gform-field-label__text'>\u00d8 (DC)<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_30' id='input_34_30' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_35\" class=\"gfield gfield--type-text gf_second_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_35'><span class='gform-field-label__text'>Length (OAL)<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_35' id='input_34_35' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_40\" class=\"gfield gfield--type-text gf_third_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_40'><span class='gform-field-label__text'>Drilling depth (mm)<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_40' id='input_34_40' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_43\" class=\"gfield gfield--type-text gf_fourth_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_43'><span class='gform-field-label__text'>Driver dimensions (DCONxLSC\/LS)<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_43' id='input_34_43' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_50\" class=\"gfield gfield--type-text gf_first_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_50'><span class='gform-field-label__text'>Driver No.<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_50' id='input_34_50' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_55\" class=\"gfield gfield--type-text gf_second_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_55'><span class='gform-field-label__text'>Coating<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_55' id='input_34_55' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_60\" class=\"gfield gfield--type-text gf_third_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_60'><span class='gform-field-label__text'>Pieces<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_60' id='input_34_60' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_65\" class=\"gfield gfield--type-text gf_fourth_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_65'><span class='gform-field-label__text'>Delivery date<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_65' id='input_34_65' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_26\" class=\"gfield gfield--type-html gfield_html gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h3>Drill 5<\/h3><\/li><li id=\"field_34_31\" class=\"gfield gfield--type-text gf_first_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_31'><span class='gform-field-label__text'>\u00d8 (DC)<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_31' id='input_34_31' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_36\" class=\"gfield gfield--type-text gf_second_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_36'><span class='gform-field-label__text'>Length (OAL)<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_36' id='input_34_36' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_41\" class=\"gfield gfield--type-text gf_third_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_41'><span class='gform-field-label__text'>Drilling depth (mm)<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_41' id='input_34_41' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_46\" class=\"gfield gfield--type-text gf_fourth_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_46'><span class='gform-field-label__text'>Driver dimensions (DCONxLSC\/LS)<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_46' id='input_34_46' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_51\" class=\"gfield gfield--type-text gf_first_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_51'><span class='gform-field-label__text'>Driver No.<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_51' id='input_34_51' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_56\" class=\"gfield gfield--type-text gf_second_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_56'><span class='gform-field-label__text'>Coating<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_56' id='input_34_56' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_61\" class=\"gfield gfield--type-text gf_third_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_61'><span class='gform-field-label__text'>Pieces<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_61' id='input_34_61' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_66\" class=\"gfield gfield--type-text gf_fourth_quarter field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_66'><span class='gform-field-label__text'>Delivery date<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_66' id='input_34_66' type='text' value='' class='small'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_34_70\" class=\"gfield gfield--type-section gsection field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h2 class=\"gsection_title\"><\/h2><\/li><li id=\"field_34_69\" class=\"gfield gfield--type-html gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div style=\"margin-top: 40px;\">\n<img decoding=\"async\" style=\"display: block; margin: auto;\" src=\"https:\/\/www.botek.de\/wp-content\/uploads\/2023\/03\/Lagerprogramm_pibo.png\" width=\"80%\" border=\"0\" \/>\n<\/div><\/li><li id=\"field_34_67\" class=\"gfield gfield--type-section gsection field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h2 class=\"gsection_title\"><\/h2><\/li><li id=\"field_34_71\" class=\"gfield gfield--type-checkbox gfield--type-choice field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible gfield--choice-align-vertical\"  ><label class='gfield_label gform-field-label screen-reader-text gfield_label_before_complex' ><span class='gform-field-label__text'><\/span><\/label><div class='ginput_container ginput_container_checkbox'><ul class='gfield_checkbox' id='input_34_71'><li class='gchoice gchoice_34_71_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_71.1' type='checkbox'  value='Type 158-07 Solid carbide pilot drill not coolant fed'  id='choice_34_71_1'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_34_71_1' id='label_34_71_1' class='gform-field-label gform-field-label--type-inline'>Type 158-07 Solid carbide pilot drill not coolant fed<\/label>\n\t\t\t\t\t\t\t<\/li><li class='gchoice gchoice_34_71_2'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_71.2' type='checkbox'  value='Type 158-08 Solid carbide pilot drill coolant fed'  id='choice_34_71_2'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_34_71_2' id='label_34_71_2' class='gform-field-label gform-field-label--type-inline'>Type 158-08 Solid carbide pilot drill coolant fed<\/label>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/li><li id=\"field_34_72\" class=\"gfield gfield--type-section gsection field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h2 class=\"gsection_title\"><\/h2><\/li><li id=\"field_34_73\" class=\"gfield gfield--type-textarea field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_34_73'><span class='gform-field-label__text'>Remark:<\/span><\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_73' id='input_34_73' class='textarea medium'      aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/li><li id=\"field_34_74\" class=\"gfield gfield--type-section gsection field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h2 class=\"gsection_title\"><\/h2><\/li><li id=\"field_34_75\" class=\"gfield gfield--type-checkbox gfield--type-choice gfield--width-full gf_list_inline field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible gfield--choice-align-vertical\"  ><label class='gfield_label gform-field-label gfield_label_before_complex' ><span class='gform-field-label__text'>Mode of shipment:<\/span><\/label><div class='ginput_container ginput_container_checkbox'><ul class='gfield_checkbox' id='input_34_75'><li class='gchoice gchoice_34_75_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_75.1' type='checkbox'  value='UPS (delivery within 2 working days)'  id='choice_34_75_1'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_34_75_1' id='label_34_75_1' class='gform-field-label gform-field-label--type-inline'>UPS (delivery within 2 working days)<\/label>\n\t\t\t\t\t\t\t<\/li><li class='gchoice gchoice_34_75_2'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_75.2' type='checkbox'  value='TNT 9.00 a.m.'  id='choice_34_75_2'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_34_75_2' id='label_34_75_2' class='gform-field-label gform-field-label--type-inline'>TNT 9.00 a.m.<\/label>\n\t\t\t\t\t\t\t<\/li><li class='gchoice gchoice_34_75_3'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_75.3' type='checkbox'  value='TNT 12.00 a.m.'  id='choice_34_75_3'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_34_75_3' id='label_34_75_3' class='gform-field-label gform-field-label--type-inline'>TNT 12.00 a.m.<\/label>\n\t\t\t\t\t\t\t<\/li><li class='gchoice gchoice_34_75_4'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_75.4' type='checkbox'  value='Pick up'  id='choice_34_75_4'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_34_75_4' id='label_34_75_4' class='gform-field-label gform-field-label--type-inline'>Pick up<\/label>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/li><li id=\"field_34_85\" class=\"gfield gfield--type-section gsection field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h2 class=\"gsection_title\"><\/h2><\/li><\/ul><\/div>\n        <div class='gform-footer gform_footer top_label'> <button type='submit' id='gform_submit_button_34' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' >SEND<\/button> \n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_34' value='postback' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_34' id='gform_theme_34' value='legacy' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_34' id='gform_style_settings_34' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_34' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='34' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='EUR' value='Qslzu\/DVtQaHGQMi6pbuhjxoP6ojtj0JwQSTQAsb+yAuiz5q3xwrHvtJjuMhM9GpUWjYskikWQ64BIugNkLcE9ecCDpMSj+jLSr4GqvO240Ydas=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_34' value='WyJ7XCJnZm9ybV9zdWJtaXNzaW9uX21ldGhvZFwiOltcIjcxZmY3ODU4MzBjNWNjY2I4MGRmMTIyZTIxN2JmMzRjXCIsXCIzYmM5ZWVkNzRjOWM3Y2VjOGU5NzQxYWJjNjc0MWVhMlwiXSxcImdmb3JtX3RoZW1lXCI6XCIyNDU2ZDE1MTZhYWIwMDZjNGFlYzgyOGQ1ODM1ZDFhZVwiLFwiZ2Zvcm1fc3R5bGVfc2V0dGluZ3NcIjpcIjEwZGM0MGY2NTlmYTM2YzZhNDRmMmMzMGJmZDQ1Y2I3XCIsXCJmb3JtX2lkXCI6XCI0YzBlYmRmYjZlOTA0ODU4YzMwOGFmZTY1YzkwMTI1ZlwiLFwidXJsXCI6XCJjZjBjOGQxYWM4OWUxN2U0MDA3M2ZiM2MzOTRhMmM0MFwiLFwic3RhdGVfdGltZXN0YW1wXCI6XCJkYzZhOWE2Y2QzMjdmY2ZjZmEzMThlMDM5NDNhYTgwZVwifSIsImZlYjM2YmRlNDZkZGYzMzEzNzUwM2QxYWZkZDAyNGZiIiwxNzg4MzY0OTY2XQ==' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_34' id='gform_target_page_number_34' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_34' id='gform_source_page_number_34' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            <input type='hidden' name='gform_uploaded_files' id='gform_uploaded_files_34' value='' \/>\n        <\/div>\n                        <\/form>\n                        <\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":925,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-17009","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.botek.de\/en\/wp-json\/wp\/v2\/pages\/17009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.botek.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.botek.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.botek.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.botek.de\/en\/wp-json\/wp\/v2\/comments?post=17009"}],"version-history":[{"count":0,"href":"https:\/\/www.botek.de\/en\/wp-json\/wp\/v2\/pages\/17009\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.botek.de\/en\/wp-json\/wp\/v2\/pages\/925"}],"wp:attachment":[{"href":"https:\/\/www.botek.de\/en\/wp-json\/wp\/v2\/media?parent=17009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}